{"id":246,"date":"2022-06-02T21:25:53","date_gmt":"2022-06-03T02:25:53","guid":{"rendered":"http:\/\/ciencianews.in\/?p=246"},"modified":"2022-06-02T21:25:55","modified_gmt":"2022-06-03T02:25:55","slug":"dotan-de-tecnologia-a-alumnos-del-cobaq","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/06\/02\/dotan-de-tecnologia-a-alumnos-del-cobaq\/","title":{"rendered":"Dotan de tecnolog\u00eda a alumnos del Cobaq."},"content":{"rendered":"\n<p>Los estudiantes del plantel 34 del Cobaq en San Juan del R\u00edo, Quer\u00e9taro, recibieron tabletas electr\u00f3nicas para el fortalecimiento de su proceso educativo de todos los j\u00f3venes de esta comunidad.<\/p>\n\n\n\n<p>Estas acciones forman parte de la estrategia \u201cContigo tabletas para estudiar m\u00e1s\u201d, con las que el gobierno del estado busca dotar de herramientas tecnol\u00f3gicas de actualidad a todos los estudiantes de cada escuela durante toda su gesti\u00f3n.<\/p>\n\n\n\n<p>Con ello se pretende que las comunidades, familias y personas con menor acceso a estas herramientas, puedan acceder a otras perspectivas del mundo y complementar los aprendizajes que reciben en los planteles.<\/p>\n\n\n\n<p>Igualmente, este programa pretende reducir el porcentaje de deserci\u00f3n acad\u00e9mica del estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los estudiantes del plantel 34 del Cobaq en San Juan del R\u00edo, Quer\u00e9taro, recibieron tabletas electr\u00f3nicas para el fortalecimiento de su proceso educativo de todos los j\u00f3venes de esta comunidad. Estas acciones forman parte de la estrategia \u201cContigo tabletas para estudiar m\u00e1s\u201d, con las que el gobierno del estado busca dotar de herramientas tecnol\u00f3gicas de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-246","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=246"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/246\/revisions"}],"predecessor-version":[{"id":247,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/246\/revisions\/247"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}