{"id":281,"date":"2022-06-07T10:27:42","date_gmt":"2022-06-07T15:27:42","guid":{"rendered":"http:\/\/ciencianews.in\/?p=281"},"modified":"2022-06-07T10:27:43","modified_gmt":"2022-06-07T15:27:43","slug":"agtech-lanza-nueva-app-para-monitorear-los-campos-mexicanos","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/06\/07\/agtech-lanza-nueva-app-para-monitorear-los-campos-mexicanos\/","title":{"rendered":"Agtech lanza nueva app para monitorear los campos mexicanos"},"content":{"rendered":"\n<p><strong><em>L<\/em><\/strong><strong><em>a nueva&nbsp;aplicaci\u00f3n facilita el monitoreo de los campos y asegura la m\u00e1xima eficiencia en&nbsp;el manejo&nbsp;de sus cultivos desde&nbsp;<\/em><\/strong><strong><em>cualquier dispositivo m\u00f3vil. &nbsp;<\/em><\/strong><\/p>\n\n\n\n<p>Mantener a los agricultores completamente informados, casi minuto a minuto sobre todas las necesidades de sus campos, es una de las metas que se han impuesto en la agtech&nbsp;<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/www.instacrops.com\/\">Instacrops<\/a>&nbsp;al lanzar la aplicaci\u00f3n a la que podr\u00e1n acceder directamente en su celular.<\/p>\n\n\n\n<p>\u201cLa App es un proyecto muy ambicioso, en donde los usuarios de Instacrops podr\u00e1n ver im\u00e1genes satelitales para la monitorizaci\u00f3n de los cultivos u obtener informaci\u00f3n sobre riego inteligente, recibiendo alertas sobre los requerimiento de los campos, ya sea porque viene una helada, o supervisar la humedad del suelo o su temperatura\u201d, as\u00ed lo explica Fabi\u00e1n Mart\u00ednez, Chief Agronomist de Instacrops.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo funciona?<\/strong><\/p>\n\n\n\n<p>Los usuarios de Instacrops pueden descargar la aplicaci\u00f3n disponible tanto para dispositivos Android como para iOS. Una vez instalada en el smartphone, tablet o iPad, es posible comenzar a obtener informaci\u00f3n de manera inmediata, gracias a una interfaz amigable e intuitiva que permite una comunicaci\u00f3n directa con los servicios.<\/p>\n\n\n\n<p>\u201cAl ingresar a la App, el usuario podr\u00e1 visualizar los pol\u00edgonos de sus campos, revisar informaci\u00f3n de los sectores como cantidad de hect\u00e1reas, tipo de cultivo y una leyenda de c\u00f3mo se ha estado regando. Cuando entran a la secci\u00f3n de servicios de monitoreo de par\u00e1metros de suelo, el usuario puede revisar una lista de sus estaciones InstaSoil y acceder a los datos de los sensores conectados a sus estaciones. Esto incluye la humedad del suelo a diferentes profundidades, el estanque aprovechable, entre otras. Cuando el usuario accede a los servicios de Clima, InstaWeather, puede visualizar la temperatura ambiente, humedad, presi\u00f3n atmosf\u00e9rica, radiaci\u00f3n, velocidad del viento y su direcci\u00f3n, en conjunto a diversas variables calculadas como la evapotranspiraci\u00f3n, horas fr\u00edo, porciones fr\u00edo, grados d\u00eda entre otros\u201d, agrega&nbsp;Francisco Altimiras, PhD. Chief Technology Officer, Instacrops.<\/p>\n\n\n\n<p>Para la Agtech este es un paso muy importante que les permite seguir promoviendo la democratizaci\u00f3n del acceso a tecnolog\u00eda de punta para los agricultores de Latinoam\u00e9rica. \u201cNuestra nueva App va a permitir llegar a muchos m\u00e1s usuarios que prefieren dispositivos m\u00f3viles para revisar la informaci\u00f3n de nuestros servicios. Esta aplicaci\u00f3n lleva todo el conocimiento adquirido por Instacrops a nivel Web tanto a celulares como tablets, para que nuestros usuarios puedan monitorear sus cultivos&nbsp;<em>in situ<\/em>&nbsp;mejorando la experiencia de uso de la plataforma Instacrops. Adem\u00e1s, pr\u00f3ximamente lanzaremos tambi\u00e9n una aplicaci\u00f3n m\u00f3vil gratuita de nuestra plataforma, ofreciendo pron\u00f3sticos clim\u00e1ticos como predicciones de heladas e informaci\u00f3n contenida en im\u00e1genes satelitales, agrega Francisco Altimiras.<\/p>\n\n\n\n<p>De esta manera, la app permitir\u00e1 simplificar el d\u00eda a d\u00eda de los agricultores, puesto que obtendr\u00e1n la informaci\u00f3n necesaria para un manejo inteligente de sus cultivos, contribuyendo a la optimizaci\u00f3n del uso de los recursos como agua y energ\u00eda.<\/p>\n\n\n\n<p>Esta herramienta, forma parte las nuevas prestaciones que est\u00e1 lanzando Instacrops, tal como su nuevo modelo de negocios \u201cPresicion Agriculture as a Service\u201d (PAaaS) que va de la mano de su crecimiento en toda Latinoam\u00e9rica, estando presentes en los campos de M\u00e9xico, Chile y Colombia.<\/p>\n\n\n\n<p>En 2021, la plataforma entr\u00f3 a la aceleradora estadounidense Y Combinator transform\u00e1ndose en la primera Agtech latinoamericana en ser seleccionada. A la fecha han levantado USD 3,5 millones de capitales privados liderados por Genesis Ventures -donde el principal inversionista es el grupo brit\u00e1nico OxBridge Capital Partners\u2013 y tambi\u00e9n SVG Ventures, programa de inversi\u00f3n especializado y el m\u00e1s activo de la industria Agtech en Silicon Valley. Todo esto les permiti\u00f3 mudar su matriz a Estados Unidos para lograr seguir conectando con m\u00e1s inversionistas.<\/p>\n\n\n\n<p><strong>&#8211;ooOoo&#8211;<\/strong><\/p>\n\n\n\n<p><strong>Acerca de Instacrops<\/strong><\/p>\n\n\n\n<p>Plataforma AgTech l\u00edder en la industria, que permite gestionar completamente los cultivos desde un solo software, integrando todos los servicios de monitoreo y control de par\u00e1metros claves de los campos, optimizando el uso de recursos, como agua y energ\u00eda, as\u00ed como tambi\u00e9n los procesos de producci\u00f3n y administraci\u00f3n de mano de obra. A trav\u00e9s de su tecnolog\u00eda permite a cada agricultor maximizar el rendimiento de sus cultivos por medio de un plan personalizado para sus campos. Se caracteriza tambi\u00e9n por entregar soporte multicanal durante todo el proceso y ser pioneros en el modelo de negocios PAaaS, basado en una suscripci\u00f3n anual de Software de bajo costo, que incluye el servicio completo de incorporaci\u00f3n de tecnolog\u00eda (instalaci\u00f3n, hardware y mantenci\u00f3n).<\/p>\n\n\n\n<p>luismart_ic@yahoo.com.mx<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nueva&nbsp;aplicaci\u00f3n facilita el monitoreo de los campos y asegura la m\u00e1xima eficiencia en&nbsp;el manejo&nbsp;de sus cultivos desde&nbsp;cualquier dispositivo m\u00f3vil. &nbsp; Mantener a los agricultores completamente informados, casi minuto a minuto sobre todas las necesidades de sus campos, es una de las metas que se han impuesto en la agtech&nbsp;Instacrops&nbsp;al lanzar la aplicaci\u00f3n a la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-281","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/281\/revisions\/282"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}