{"id":371,"date":"2022-06-25T15:58:39","date_gmt":"2022-06-25T20:58:39","guid":{"rendered":"http:\/\/ciencianews.in\/?p=371"},"modified":"2022-06-25T15:58:41","modified_gmt":"2022-06-25T20:58:41","slug":"el-centro-de-satelites-de-las-naciones-unidas-trabaja-para-impulsar-el-desarrollo-sostenible","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/06\/25\/el-centro-de-satelites-de-las-naciones-unidas-trabaja-para-impulsar-el-desarrollo-sostenible\/","title":{"rendered":"El Centro de Sat\u00e9lites de las Naciones Unidas Trabaja para Impulsar el Desarrollo Sostenible"},"content":{"rendered":"\n<p><strong>Comunicado<\/strong><br><strong>Ciudad de M\u00e9xico, M\u00e9xico.&nbsp;&nbsp;24 Junio 2022-<\/strong><\/p>\n\n\n\n<p><em>El programa de las Naciones Unidas acelera la gesti\u00f3n de desastres clim\u00e1ticos con la tecnolog\u00eda de NVIDIA y un curso gratuito del Instituto de Deep Learning para cient\u00edficos de datos de todo el mundo.<\/em><\/p>\n\n\n\n<p>Los mayores desaf\u00edos de la humanidad est\u00e1n interconectados. El esfuerzo para poner fin a la pobreza, por ejemplo, est\u00e1 vinculado a la mejora de la salud y la educaci\u00f3n, que depende de la reducci\u00f3n de la desigualdad. Todo esto requiere un entorno global saludable para el cual la acci\u00f3n clim\u00e1tica es crucial.<\/p>\n\n\n\n<p>Para abordar estos problemas globales, NVIDIA est\u00e1 trabajando con el Centro de Sat\u00e9lite de las Naciones Unidas (UNOSAT) para aplicar los poderes del deep learning y la IA. El esfuerzo respalda la&nbsp;<a href=\"https:\/\/sdgs.un.org\/2030agenda\" target=\"_blank\" rel=\"noreferrer noopener\">Agenda para el Desarrollo Sostenible de 2030<\/a>&nbsp;de las Naciones Unidas, que se basa en&nbsp;<a href=\"https:\/\/sdgs.un.org\/goals\" target=\"_blank\" rel=\"noreferrer noopener\">17 Objetivos de Desarrollo Sostenible<\/a>&nbsp;interrelacionados. Estos ODS, que incluyen \u00abacci\u00f3n clim\u00e1tica\u00bb y \u00abciudades y comunidades sostenibles\u00bb, sirven como llamados a la acci\u00f3n para todos los estados miembros de las Naciones Unidas con el fin de apoyar el bienestar mundial.<\/p>\n\n\n\n<p>La colaboraci\u00f3n entre UNOSAT, parte del Instituto de Capacitaci\u00f3n e Investigaci\u00f3n de las Naciones Unidas, y NVIDIA se centra inicialmente en impulsar la gesti\u00f3n de desastres relacionados con el clima mediante el uso de la IA para la Observaci\u00f3n de la Tierra. AI4EO, como se le conoce, es un t\u00e9rmino que abarca las iniciativas que utilizan la IA para ayudar a monitorear y evaluar los cambios del planeta.<\/p>\n\n\n\n<p>Para acelerar la investigaci\u00f3n y el desarrollo de sus esfuerzos en AI4EO, UNOSAT integrar\u00e1 su infraestructura de tecnolog\u00eda de im\u00e1genes satelitales con la plataforma de computaci\u00f3n acelerada de NVIDIA. El sistema de im\u00e1genes satelitales impulsadas por IA recopilar\u00e1 y analizar\u00e1 informaci\u00f3n geoespacial para proporcionar datos casi en tiempo real sobre inundaciones, incendios forestales y otros desastres relacionados con el clima.<\/p>\n\n\n\n<p>Adem\u00e1s, UNOSAT ha lanzado un m\u00f3dulo educativo que se basa en un curso del&nbsp;<a href=\"https:\/\/www.nvidia.com\/en-us\/training\/\" target=\"_blank\" rel=\"noreferrer noopener\">Deep Learning Institute de NVIDIA<\/a>&nbsp;(DLI) sobre la aplicaci\u00f3n de m\u00e9todos de deep learning para generar modelos precisos de detecci\u00f3n de inundaciones.<\/p>\n\n\n\n<p>\u00abEl trabajo con NVIDIA nos permitir\u00e1 cerrar el proceso desde la investigaci\u00f3n de IA hasta la implementaci\u00f3n de soluciones clim\u00e1ticas en el menor tiempo posible, a fin de garantizar que las poblaciones vulnerables puedan beneficiarse de la tecnolog\u00eda\u00bb, dijo Einar Bj\u00f8rgo, director de UNOSAT.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>An\u00e1lisis de Im\u00e1genes Satelitales Impulsadas por IA<\/strong><\/h2>\n\n\n\n<p>Para tareas como evaluar el impacto de un cicl\u00f3n tropical en Filipinas o la actividad volc\u00e1nica en Tonga, el servicio de mapeo de emergencia de UNOSAT utiliza visi\u00f3n de computaci\u00f3n e im\u00e1genes satelitales a fin de obtener informaci\u00f3n precisa sobre desastres complejos.<\/p>\n\n\n\n<p>El an\u00e1lisis casi en tiempo real es clave para administrar los eventos de desastre clim\u00e1tico. Los equipos humanitarios pueden utilizar los datos proporcionados por la IA para tomar medidas r\u00e1pidas y eficaces en el combate de los desastres. Los datos tambi\u00e9n se utilizan para informar pol\u00edticas de desarrollo sostenible, desarrollar las capacidades de los usuarios y fortalecer la adaptabilidad clim\u00e1tica en general.<\/p>\n\n\n\n<p>UNOSAT potenciar\u00e1 su infraestructura de tecnolog\u00eda de im\u00e1genes satelitales con&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.nvidia.com\/en-us\/data-center\/dgx-systems\/\" target=\"_blank\">los sistemas NVIDIA DGX<\/a>, que permiten el desarrollo de IA a escala, as\u00ed como la&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.nvidia.com\/en-us\/autonomous-machines\/embedded-systems\/\" target=\"_blank\">plataforma NVIDIA EGX<\/a>, que ofrece la potencia de la computaci\u00f3n acelerada desde el data center hasta el&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/blogs.nvidia.com\/blog\/2022\/02\/17\/what-is-edge-ai\/\" target=\"_blank\">edge<\/a>. La tecnolog\u00eda de NVIDIA acelera la detecci\u00f3n de inundaciones basada en IA en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.youtube.com\/watch?v=3mXPclqLdeo\" target=\"_blank\">7 veces<\/a>, para cubrir \u00e1reas m\u00e1s grandes con mayor precisi\u00f3n, seg\u00fan UNOSAT.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Curso del DLI de NVIDIA sobre Monitoreo de Riesgos de Desastres<\/strong><\/h2>\n\n\n\n<p>Adem\u00e1s de la potente tecnolog\u00eda, es esencial contar con una fuerza laboral calificada para aprovechar la IA y la ciencia de datos con el objetivo de analizar e impedir que los eventos clim\u00e1ticos se conviertan en desastres para la humanidad.<\/p>\n\n\n\n<p>\u00abNVIDIA y UNOSAT tienen una oportunidad \u00fanica para combatir el impacto del cambio clim\u00e1tico y avanzar en los ODS de la ONU, con un punto de lanzamiento de capacitaci\u00f3n a los cient\u00edficos de datos para que desarrollen e implementen modelos acelerados por GPU que mejoren la predicci\u00f3n de inundaciones\u00bb, dijo Keith Strier, vicepresidente de Iniciativas de IA globales en NVIDIA.<\/p>\n\n\n\n<p>UNOSAT desarroll\u00f3 un m\u00f3dulo para el curso gratuito y en l\u00ednea del Deep Learning Institute, que cubre c\u00f3mo desarrollar un modelo de deep learning para automatizar la detecci\u00f3n de eventos de inundaci\u00f3n. El curso se llama&nbsp;<a href=\"https:\/\/courses.nvidia.com\/courses\/course-v1:DLI+S-ES-01+V1\/\" target=\"_blank\" rel=\"noreferrer noopener\">Monitoreo de Riesgos de Desastres Utilizando Im\u00e1genes Satelitales<\/a>&nbsp;y es el primero de los muchos cursos planificados de NVIDIA que se centran en la acci\u00f3n clim\u00e1tica para la comunidad del sector p\u00fablico global.<\/p>\n\n\n\n<p>El m\u00f3dulo de UNOSAT, basado en un estudio de caso real de la ONU,destaca un ejemplo de una&nbsp;<a href=\"https:\/\/www.unitar.org\/about\/news-stories\/news\/unosat-flood-ai-dashboards-nepal-creation-one-stop-shop-real-time-evidence-based-decision-making\" target=\"_blank\" rel=\"noreferrer noopener\">inundaci\u00f3n en Nepal<\/a>.<\/p>\n\n\n\n<p>En colaboraci\u00f3n con NVIDIA, UNOSAT ofrece el m\u00f3dulo de forma gratuita con el objetivo de capacitar a los cient\u00edficos de datos de todo el mundo a fin de aprovechar la computaci\u00f3n acelerada y predecir y responder a desastres relacionados con el clima. \u00abNuestro objetivo es democratizar el acceso a la computaci\u00f3n acelerada para ayudar a las naciones a entrenar modelos de deep learning m\u00e1s precisos que predicen y responden mejor a todo un espectro de desastres naturales y para la humanidad\u00bb, dijo Strier.<\/p>\n\n\n\n<p>Comienza con el curso, que ya est\u00e1 disponible en&nbsp;<a href=\"https:\/\/event.unitar.org\/full-catalog\/disaster-risk-monitoring-using-satellite-imagery\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/event.unitar.org\/full-catalog\/disaster-risk-monitoring-using-satellite-imagery<\/a>.<\/p>\n\n\n\n<p><em><u><a href=\"https:\/\/www.nvidia.com\/en-us\/on-demand\/playlist\/playList-b746d233-c8dd-484c-8fa5-be1af88cbda3\/\" target=\"_blank\" rel=\"noreferrer noopener\">Obt\u00e9n m\u00e1s informaci\u00f3n<\/a><\/u><\/em><em>&nbsp;sobre c\u00f3mo se usa la tecnolog\u00eda NVIDIA para mejorar el planeta y su gente.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ComunicadoCiudad de M\u00e9xico, M\u00e9xico.&nbsp;&nbsp;24 Junio 2022- El programa de las Naciones Unidas acelera la gesti\u00f3n de desastres clim\u00e1ticos con la tecnolog\u00eda de NVIDIA y un curso gratuito del Instituto de Deep Learning para cient\u00edficos de datos de todo el mundo. Los mayores desaf\u00edos de la humanidad est\u00e1n interconectados. El esfuerzo para poner fin a la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-371","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=371"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/371\/revisions"}],"predecessor-version":[{"id":372,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/371\/revisions\/372"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}