{"id":382,"date":"2022-06-27T21:19:42","date_gmt":"2022-06-28T02:19:42","guid":{"rendered":"http:\/\/ciencianews.in\/?p=382"},"modified":"2022-06-27T21:19:44","modified_gmt":"2022-06-28T02:19:44","slug":"fomenta-la-unam-vocacion-temprana-para-la-investigacion-cientifica","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/06\/27\/fomenta-la-unam-vocacion-temprana-para-la-investigacion-cientifica\/","title":{"rendered":"Fomenta la UNAM vocaci\u00f3n temprana para la investigaci\u00f3n cient\u00edfica"},"content":{"rendered":"\n<p><strong>Autor<\/strong><br>Direcci\u00f3n General de Comunicaci\u00f3n Social, UNAM<br><strong>Fecha de publicaci\u00f3n<\/strong><br>27 de junio de 2022<br><strong>Categor\u00eda<\/strong><br>Bolet\u00edn<\/p>\n\n\n\n<p><em>\u2022 Concluy\u00f3 el Programa de Estancias Cortas del IQ; participaron 54 estudiantes del bachillerato universitario y de instituciones privadas<\/em><em><br>\u2022 Habr\u00e1n aprendido a evaluar con conocimiento, raz\u00f3n y datos un argumento que se sustenta o no, dijo William Lee Alard\u00edn<br>\u2022 Esperamos que con este primer contacto se despierte en los j\u00f3venes el gusto, amor y pasi\u00f3n por la ciencia: Luis Demetrio Miranda Guti\u00e9rrez<\/em><\/p>\n\n\n\n<p>La Qu\u00edmica est\u00e1 cada vez m\u00e1s en investigaciones o temas relacionados con salud, medio ambiente, preservaci\u00f3n de biodiversidad, cambio clim\u00e1tico y, en general, con sustentabilidad, afirm\u00f3 el coordinador de la Investigaci\u00f3n Cient\u00edfica de la UNAM, William Lee Alard\u00edn.<\/p>\n\n\n\n<p>Durante la clausura de la edici\u00f3n 2022 del Programa de Estancias Cortas de Investigaci\u00f3n \u2013impulsado por el Instituto de Qu\u00edmica (IQ)\u2013, en el cual alumnos de bachillerato elaboraron un trabajo de investigaci\u00f3n propio en un laboratorio calificado, durante seis meses, argument\u00f3:<\/p>\n\n\n\n<p>\u201cEstas vertientes requieren una base muy s\u00f3lida, pero tambi\u00e9n establecer lazos con otras disciplinas para entender de qu\u00e9 manera se pueden aplicar esas herramientas a muchos problemas muy diversos que necesitamos resolver urgentemente\u201d.<\/p>\n\n\n\n<p>Lee Alard\u00edn enfatiz\u00f3 en su mensaje: \u201crequerimos de todas y todos ustedes ahorita, dentro de cinco, de diez a\u00f1os, para que nos ayuden a resolver los problemas que tenemos, no solo en M\u00e9xico sino a nivel global\u201d.<\/p>\n\n\n\n<p>Con estas estancias, agreg\u00f3, habr\u00e1n aprendido a evaluar con conocimiento, raz\u00f3n y datos en la mano, un argumento que se sustenta o no, y eso les servir\u00e1 a lo que se dediquen.<\/p>\n\n\n\n<p>A su vez, el director del IQ, Luis Demetrio Miranda Guti\u00e9rrez, asegur\u00f3 durante la ceremonia de clausura realizada en el vest\u00edbulo del Museo de las Ciencias&nbsp;<em>Universum<\/em>:<\/p>\n\n\n\n<p>Esperamos que con este primer contacto se despierte en nuestros j\u00f3venes el gusto, el amor, la pasi\u00f3n por la ciencia y que se decanten por una carrera en este \u00e1mbito.<\/p>\n\n\n\n<p>\u00a1Cr\u00e9anlo desde ahora, ustedes pueden llegar a ser grandes cient\u00edficos!, dijo ante los 54 estudiantes del Programa provenientes de diversos planteles de la Escuela Nacional Preparatoria (ENP), el Colegio de Ciencias y Humanidades (CCH), del Programa de J\u00f3venes a la Investigaci\u00f3n, y de colegios particulares como Madrid, Sim\u00f3n Bol\u00edvar, Preparatoria y Universidad La Salle, adem\u00e1s del Instituto Miguel \u00c1ngel.<\/p>\n\n\n\n<p>Los alumnos mostraron los resultados de sus investigaciones a trav\u00e9s de carteles, actividad que de acuerdo con el director les brinda experiencia, formaci\u00f3n y criterio cient\u00edfico. \u201cLo que hoy han experimentado es exactamente igual a una sesi\u00f3n de carteles de las que se desarrollan en cualquier congreso, en donde se muestran los avances cient\u00edficos m\u00e1s recientes\u201d.<\/p>\n\n\n\n<p>En su oportunidad, el coordinador de Vinculaci\u00f3n y Transferencia Tecnol\u00f3gica de la Universidad Nacional, Jorge V\u00e1zquez Ramos, afirm\u00f3 que la Qu\u00edmica est\u00e1 en todo.<\/p>\n\n\n\n<p>\u201cNo hay nada que no la tenga, v\u00e9anlo por donde quieran: la silla donde est\u00e1n, la formaci\u00f3n de nuestras c\u00e9lulas, lo que comemos, incluso dos seres humanos pueden hacer qu\u00edmica entre s\u00ed, de esta manera aceptarse o rechazarse como cualquier proceso cient\u00edfico\u201d.<\/p>\n\n\n\n<p>El tambi\u00e9n exdirector de la Facultad de Qu\u00edmica pidi\u00f3 a los estudiantes apoyar el desarrollo del pa\u00eds \u201cque mucho requiere de mentes j\u00f3venes que impulsen la ciencia, la tecnolog\u00eda y el bienestar de la humanidad\u201d.<\/p>\n\n\n\n<p>En el acto estuvieron, adem\u00e1s: la jefa del Departamento de Qu\u00edmica de la ENP, Olivia Rodr\u00edguez Zavala; la secretaria de Servicios de Apoyo al Aprendizaje de la Direcci\u00f3n General de CCH, Martha Patricia L\u00f3pez Abundio; as\u00ed como representantes de la Preparatoria y la Universidad La Salle, la Preparatoria Sim\u00f3n Bol\u00edvar y el Instituto Miguel \u00c1ngel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutorDirecci\u00f3n General de Comunicaci\u00f3n Social, UNAMFecha de publicaci\u00f3n27 de junio de 2022Categor\u00edaBolet\u00edn \u2022 Concluy\u00f3 el Programa de Estancias Cortas del IQ; participaron 54 estudiantes del bachillerato universitario y de instituciones privadas\u2022 Habr\u00e1n aprendido a evaluar con conocimiento, raz\u00f3n y datos un argumento que se sustenta o no, dijo William Lee Alard\u00edn\u2022 Esperamos que con este [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-382","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=382"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/382\/revisions"}],"predecessor-version":[{"id":383,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/382\/revisions\/383"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}