{"id":407,"date":"2022-07-12T20:37:20","date_gmt":"2022-07-13T01:37:20","guid":{"rendered":"http:\/\/ciencianews.in\/?p=407"},"modified":"2022-07-12T20:37:21","modified_gmt":"2022-07-13T01:37:21","slug":"el-conacyt-publica-convocatoria-para-becas-de-doctorados-en-el-extranjero-en-ciencias-y-humanidades","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/07\/12\/el-conacyt-publica-convocatoria-para-becas-de-doctorados-en-el-extranjero-en-ciencias-y-humanidades\/","title":{"rendered":"El Conacyt publica convocatoria para becas de doctorados en el extranjero en ciencias y humanidades\u00a0"},"content":{"rendered":"\n<p><strong>Autor<\/strong><br>Consejo Nacional de Ciencia y Tecnolog\u00eda (Conacyt)<br><strong>Fecha de publicaci\u00f3n<\/strong><br>11 de julio 2022<br><strong>Categor\u00eda<\/strong><br>Comunicado<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em>La recepci\u00f3n de solicitudes inicia el 11 de julio y concluye el 12 de agosto del presente a\u00f1o.<\/em><\/li><li><em>Los resultados se dar\u00e1n a conocer a partir del 30 de septiembre de 2022.<\/em><\/li><li><em>Los montos de la beca est\u00e1n definidos de acuerdo al tabulador de regiones y pa\u00edses donde se realice el programa de estudio.<\/em><\/li><li><em>Los apoyos contribuyen al fortalecimiento de las capacidades de las HCTI en M\u00e9xico<\/em>.<\/li><\/ul>\n\n\n\n<p>El Consejo Nacional de Ciencia y Tecnolog\u00eda (Conacyt) inicia la recepci\u00f3n de solicitudes para participar en el proceso de selecci\u00f3n para obtener una beca de posgrado al extranjero, en el marco de la convocatoria&nbsp;<em><strong>Doctorados en ciencias y humanidades en el extranjero 2022<\/strong><\/em>, dirigida a personas profesionistas de nacionalidad mexicana aceptadas e inscritas en programas presenciales y de tiempo completo en instituciones de educaci\u00f3n superior en el extranjero.<\/p>\n\n\n\n<p>El objetivo es fortalecer las capacidades nacionales en \u00e1mbitos espec\u00edficos y prioritarios en los campos de las humanidades, artes, ciencias, tecnolog\u00edas e innovaci\u00f3n, mediante el apoyo a estudiantes que al terminar sus estudios regresen al pa\u00eds para contribuir al desarrollo y bienestar del pueblo de M\u00e9xico.&nbsp;<\/p>\n\n\n\n<p>Las personas interesadas en postular a una beca en la convocatoria deber\u00e1n estar admitidas en programas presenciales para realizar estudios de doctorado por un periodo mayor a seis meses en campos de atenci\u00f3n prioritaria de las \u00e1reas de f\u00edsico-matem\u00e1ticas, ciencias de la tierra, qu\u00edmico-biol\u00f3gicas, medicina y ciencias de la salud, ciencias sociales, artes y humanidades, biotecnolog\u00eda, ciencias agropecuarias e ingenier\u00edas. Adem\u00e1s de contar la Clave \u00danica de Registro de Poblaci\u00f3n (CURP), deber\u00e1n crear o actualizar el Curr\u00edculum Vitae \u00danico (CVU) en la plataforma del Conacyt, as\u00ed como enviar la solicitud en l\u00ednea adjuntando toda la documentaci\u00f3n acad\u00e9mica y administrativa conforme a la gu\u00eda de postulaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Las personas seleccionadas para recibir una beca de posgrado en el extranjero de la convocatoria&nbsp;<em><strong>Doctorados en ciencias y humanidades en el extranjero 2022<\/strong><\/em>, recibir\u00e1n un apoyo econ\u00f3mico mensual, de acuerdo con el tabulador de divisas del pa\u00eds donde se encuentren cursando el programa de estudios; el pago de colegiatura anual apegado a los criterios de la convocatoria, adem\u00e1s de un apoyo anual para el seguro m\u00e9dico.&nbsp;<\/p>\n\n\n\n<p>La vigencia de esta beca ser\u00e1 por tiempo determinado, de conformidad con la duraci\u00f3n oficial del programa de estudios en el extranjero, sin que rebase la vigencia m\u00e1xima establecida en el Reglamento de Becas del Conacyt. Las becas se asignar\u00e1n a partir de septiembre de 2022, y en los casos cuyo inicio del programa sea posterior a esa fecha se asignar\u00e1 conforme al d\u00eda establecido en la carta de aceptaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Es importante destacar que no se asignar\u00e1n becas cuyo programa de estudios inicie despu\u00e9s del 31 de marzo de 2023 y, en los casos cuyo inicio del programa sea anterior a septiembre de 2022, la beca s\u00f3lo cubrir\u00e1 el per\u00edodo faltante para concluirlo de acuerdo con la duraci\u00f3n oficial de estudios, sin que dicho per\u00edodo exceda el plazo m\u00e1ximo establecido en el Reglamento de Becas antes mencionado.&nbsp;<\/p>\n\n\n\n<p>La recepci\u00f3n de solicitudes inicia el 11 de julio y concluye el 12 de agosto del presente a\u00f1o a las 23:59 horas, tiempo del centro de M\u00e9xico. Se prev\u00e9 un periodo adicional para&nbsp;atender inconsistencias, del 15 al 26 de agosto. La publicaci\u00f3n de resultados se dar\u00e1 a conocer en el portal del Conacyt a partir del 30 de septiembre de 2022.&nbsp;<\/p>\n\n\n\n<p>Las Bases de la Convocatoria pueden consultarse a trav\u00e9s del siguiente v\u00ednculo:&nbsp;<a href=\"https:\/\/bit.ly\/3nPMDE6%C2%A0\">https:\/\/bit.ly\/3nPMDE6&nbsp;<\/a><\/p>\n\n\n\n<p>Para mayor informaci\u00f3n, las y los interesados pueden comunicarse a trav\u00e9s del correo:\u00a0<a href=\"mailto:asignacionbextx@conacyt.mx\">asignacionbextx@conacyt.mx<\/a><br>______________________<br><a href=\"mailto:samcarbajalreportera@gmail.com\">samcarbajalreportera@gmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutorConsejo Nacional de Ciencia y Tecnolog\u00eda (Conacyt)Fecha de publicaci\u00f3n11 de julio 2022Categor\u00edaComunicado La recepci\u00f3n de solicitudes inicia el 11 de julio y concluye el 12 de agosto del presente a\u00f1o. Los resultados se dar\u00e1n a conocer a partir del 30 de septiembre de 2022. Los montos de la beca est\u00e1n definidos de acuerdo al tabulador [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-407","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=407"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/407\/revisions"}],"predecessor-version":[{"id":408,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/407\/revisions\/408"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}