{"id":419,"date":"2022-07-15T11:00:00","date_gmt":"2022-07-15T16:00:00","guid":{"rendered":"http:\/\/ciencianews.in\/?p=419"},"modified":"2022-07-15T00:00:16","modified_gmt":"2022-07-15T05:00:16","slug":"en-morelos-ipn-inaugura-centro-de-investigacion-en-ciencia-aplicada-y-tecnologia-avanzada","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/07\/15\/en-morelos-ipn-inaugura-centro-de-investigacion-en-ciencia-aplicada-y-tecnologia-avanzada\/","title":{"rendered":"En Morelos, IPN inaugura Centro de Investigaci\u00f3n en Ciencia Aplicada y Tecnolog\u00eda Avanzada"},"content":{"rendered":"\n<p><strong>Autor<\/strong><br>Instituto Polit\u00e9cnico Nacional (IPN)<br><strong>Fecha de publicaci\u00f3n<\/strong><br>13 de julio 2022<br><strong>Categor\u00eda<\/strong><br>Comunicado<\/p>\n\n\n\n<p>Con inversi\u00f3n de m\u00e1s de 150 millones de pesos en construcci\u00f3n y equipamiento, el Instituto Polit\u00e9cnico Nacional (IPN) y el gobierno del estado de Morelos inauguraron el Centro de Investigaci\u00f3n en Ciencia Aplicada y Tecnolog\u00eda Avanzada (Cicata), Unidad Morelos.<\/p>\n\n\n\n<p>Durante el acto, el director general del IPN, Arturo Reyes Sandoval, acompa\u00f1ado del gobernador del estado, Cuauht\u00e9moc Blanco Bravo, se\u00f1al\u00f3 que el complejo ser\u00e1 el primero en impartir el posgrado en Ciencia y Tecnolog\u00eda de Vacunas y Bioterap\u00e9uticos del pa\u00eds, donde saldr\u00e1n tecn\u00f3logos a nivel nacional e internacional que impulsar\u00e1n al sector farmac\u00e9utico nacional.<\/p>\n\n\n\n<p>Afirm\u00f3 que a partir de las experiencias que dej\u00f3 la pandemia por COVID-19, qued\u00f3 demostrado que la investigaci\u00f3n cient\u00edfica es primordial para dar soluci\u00f3n a los problemas derivados de esta enfermedad.<\/p>\n\n\n\n<p>Destac\u00f3 que durante 86 a\u00f1os, el IPN se ha dedicado a dar soluci\u00f3n a los grandes retos que enfrentan M\u00e9xico y la humanidad.<\/p>\n\n\n\n<p>Reyes Sandoval explic\u00f3 que Morelos tiene 35 unidades econ\u00f3micas de manufactura de productos farmac\u00e9uticos que requieren de personal altamente capacitado, servicios de formaci\u00f3n continua y servicios tecnol\u00f3gicos especializados para investigaci\u00f3n, desarrollo y mejora de procesos.<\/p>\n\n\n\n<p>Asegur\u00f3 que con el Cicata, Morelos se fortalecer\u00e1 a mediano plazo en el ecosistema de innovaci\u00f3n en el sector farmac\u00e9utico.<\/p>\n\n\n\n<p>Asimismo, record\u00f3 que la regi\u00f3n centro-sur del pa\u00eds, constituida por la Ciudad de M\u00e9xico, Estado de M\u00e9xico y Morelos, concentra 42 por ciento de unidades econ\u00f3micas de manufactura de productos farmac\u00e9uticos.<\/p>\n\n\n\n<p>La secretaria de Investigaci\u00f3n y Posgrado del IPN, Laura Arreola Mendoza, indic\u00f3 que el proyecto del Cicata nace para atender las necesidades actuales y con enfoque de pertinencia futura que contribuir\u00e1 al bienestar de la poblaci\u00f3n mexicana y, por la naturaleza e impacto de sus investigaciones, tambi\u00e9n del mundo.<\/p>\n\n\n\n<p>\u201cAnte la pandemia y el incremento en la aparici\u00f3n de enfermedades infecciosas con potencial epid\u00e9mico y las enfermedades cr\u00f3nicas que impactan la salud de los mexicanos, es necesario proveer opciones accesibles e innovadoras que permitan preservar o reestablecer la salud humana.\u201d<\/p>\n\n\n\n<p>Las instalaciones de Cicata, Unidad Morelos fue posible por la donaci\u00f3n de terrenos por parte del gobierno morelense hace 12 a\u00f1os, en tanto que la construcci\u00f3n y equipamiento se logr\u00f3 con aportaciones de diferentes fuentes.<\/p>\n\n\n\n<p>Una de ellas fue Fundaci\u00f3n Polit\u00e9cnico A.C., que don\u00f3 el equipamiento del aire acondicionado para el ala este y primer piso, adem\u00e1s de equipos de c\u00f3mputo para el uso y aprovechamiento de los laboratorios.<\/p>\n\n\n\n<p>Por su parte, el gobernador Cuauht\u00e9moc Blanco afirm\u00f3 que el Cicata Morelos representa una nueva oportunidad para el avance de la regi\u00f3n e impacta en la generaci\u00f3n de empleos e impulsa el desarrollo de talento cient\u00edfico local y nacional. \u201cCon esta obra se fomentar\u00e1 tambi\u00e9n la competitividad en Morelos y la regi\u00f3n centro del pa\u00eds. Es una muestra de la cercan\u00eda del gobierno federal con los morelenses\u201d.<\/p>\n\n\n\n<p>La secretaria de Desarrollo Econ\u00f3mico y del Trabajo de Morelos, Ana Cecilia Rodr\u00edguez Gonz\u00e1lez, detall\u00f3 que el IPN y el gobierno estatal culminan una historia de 10 a\u00f1os de trabajo colaborativo enfocado a la creaci\u00f3n del Cicata. \u201cEs un orgullo para Morelos ser aliado de una instituci\u00f3n de gran prestigio internacional como el Polit\u00e9cnico\u201d.<\/p>\n\n\n\n<p>En este marco se firmaron dos convenios de colaboraci\u00f3n: el primero, entre el IPN y el Fideicomiso Ejecutivo del Fondo de Competitividad y Promoci\u00f3n del Empleo (Fidecomp); el segundo, entre esta casa de estudios y la Secretar\u00eda de Desarrollo Econ\u00f3mico y del Trabajo de Morelos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutorInstituto Polit\u00e9cnico Nacional (IPN)Fecha de publicaci\u00f3n13 de julio 2022Categor\u00edaComunicado Con inversi\u00f3n de m\u00e1s de 150 millones de pesos en construcci\u00f3n y equipamiento, el Instituto Polit\u00e9cnico Nacional (IPN) y el gobierno del estado de Morelos inauguraron el Centro de Investigaci\u00f3n en Ciencia Aplicada y Tecnolog\u00eda Avanzada (Cicata), Unidad Morelos. Durante el acto, el director general del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-419","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=419"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/419\/revisions"}],"predecessor-version":[{"id":420,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/419\/revisions\/420"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}