{"id":502,"date":"2022-07-30T12:43:18","date_gmt":"2022-07-30T17:43:18","guid":{"rendered":"http:\/\/ciencianews.in\/?p=502"},"modified":"2022-07-30T12:43:20","modified_gmt":"2022-07-30T17:43:20","slug":"conectividad-con-alto-ancho-de-banda-y-baja-latencia-la-columna-vertebral-del-metaverso","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/07\/30\/conectividad-con-alto-ancho-de-banda-y-baja-latencia-la-columna-vertebral-del-metaverso\/","title":{"rendered":"Conectividad con alto ancho de banda y baja latencia: la columna vertebral del metaverso"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Ciudad de M\u00e9xico, julio de 2022.-&nbsp;<\/strong>El metaverso gan\u00f3 el centro del escenario: este nuevo universo virtual e inmersivo que redefine la manera en que las personas interact\u00faan, se entretienen y trabajan, implica tambi\u00e9n nuevos desaf\u00edos para las organizaciones. El llamado \u201cmetaverso industrial\u201d o \u201cmetaverso de negocios\u201d promueve nuevos espacios para lanzar productos, realizar eventos con clientes, hacer demostraciones a distancia, exponer nuevas experiencias para los consumidores o impulsar la colaboraci\u00f3n entre los miembros del equipo, entre otros numerosos casos de uso.&nbsp;&nbsp;No existen l\u00edmites: la combinaci\u00f3n de tecnolog\u00edas 3D, realidad virtual y realidad aumentada,&nbsp;<em>big data<\/em>, computaci\u00f3n de alto rendimiento e inteligencia artificial permite simular cualquier situaci\u00f3n o construir gemelos digitales, es decir, reproducciones de elementos de la realidad (desde una m\u00e1quina hasta una f\u00e1brica, desde una red el\u00e9ctrica hasta un recorrido de ferrocarril y desde un edificio hasta una ciudad entera) para hacer pruebas o cambios de situaciones hipot\u00e9ticas con muy bajo costo, sin demoras y sin riesgos de disrupci\u00f3n. As\u00ed, aquellos elementos que tienen \u00e9xito luego se pueden implementar en la realidad. Por ejemplo, un equipo t\u00e9cnico que debe probar el motor de un autom\u00f3vil ante diferentes circunstancias puede sentir la aceleraci\u00f3n, la velocidad, los ruidos y muchas otras variables.&nbsp;&nbsp;La columna vertebral para el funcionamiento del&nbsp;<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/OnAsEkXWUfPnzBt8hIPNWkRWGhWYOpqNch0LNob08m1K3yibWYLWTjcURTVUlI95vtIScHKSZnwktj-8cLFLNQTM0DJASa0wOiyKpNdpWtLbVzgeEMsbIoBX9jR8Tk2HyzcZGrA1iCzh8so7uw0UwHD-mInrHXUb0sFX-EKOOaNavmPGG1KfcbAgczNs3yoUYmAf7CHo\">metaverso<\/a>, desde el punto de vista de la tecnolog\u00eda, es internet: puede estar&nbsp;<em>hosteado<\/em>&nbsp;tanto en la nube como en el borde. Para entregar la mejor experiencia, la conectividad debe proveer altos niveles de ancho de banda y la m\u00ednima latencia.&nbsp;&nbsp;Es que el procesamiento y la transferencia de una enorme cantidad de datos en tiempo real, la velocidad de respuesta y el extremo a extremo en redes son claves: se trata de entornos multiusuario en los cuales todos los avatares (o usuarios) deben ver la misma realidad. Las acciones de cada uno de ellos -un movimiento, algo que dice, un elemento que muestra o comparte- impactan sobre todos los dem\u00e1s. Una demora de apenas un segundo puede \u201cromper\u201d la sensaci\u00f3n de realidad de este universo alternativo.&nbsp;&nbsp;<em>\u201cEl servicio de infraestructura de redes que respalde a los metaversos debe estar&nbsp;<\/em><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/EdavmcFBKzCuxr8BzSSgtwA56k8A9j0qwr1LSZ6nF3id02grHjPq8VF4nJPCIjHUKeLaor7BHzvgxe1YRuxQneiLNo_ipvs5igghJY532tSXqvEU3ZYp7Fsrb-9IP0_WIVtNhxADgkTx7QbrEORCl44wcI8cB7j2kZ2yRNhface4gf2ObwQTpQGvYGw_uUVPSXXFtu6u\"><em>altamente interconectado<\/em><\/a><em>&nbsp;para minimizar la latencia, proveer propuestas de borde para acercar el procesamiento al lugar en que se producen los hechos y brindar el m\u00e1ximo ancho de banda para soportar experiencias inmersivas y complejas con la m\u00e1xima calidad\u201d<\/em>, sostiene Alejandro Girardotti, Director Regional de Conectividad y Contenido de Lumen LATAM.&nbsp;&nbsp;La Plataforma Lumen combina una red de fibra \u00f3ptica para vincular diferentes nubes -tanto p\u00fablicas como privadas, el&nbsp;<em>edge<\/em>&nbsp;y los extremos-, servicios gestionados de extremo a extremo y una capacidad de procesamiento de baja latencia para cualquier tipo de aplicaci\u00f3n que, en conjunto, garantizan los niveles de desempe\u00f1o, flexibilidad, agilidad y seguridad que requiere el metaverso.\u00ad\u00ad\u00ad\u00ad\u00ad<\/td><\/tr><tr><td>\u00ad\u00ad\u00adAcerca de Lumen Technologies&nbsp;<strong>Lumen se gu\u00eda por la convicci\u00f3n de que la humanidad est\u00e1 en su mejor estado cuando la tecnolog\u00eda mejora nuestra forma de vivir y trabajar. Con aproximadamente 720.000 km de rutas de fibra y prestando servicios a clientes en m\u00e1s de 60 pa\u00edses, entregamos la plataforma m\u00e1s r\u00e1pida y segura para aplicaciones y datos, para ayudar a empresas, gobiernos y comunidades a entregar experiencias incre\u00edbles. Conozca m\u00e1s acerca de las soluciones de red, nube de borde, seguridad, comunicaci\u00f3n y colaboraci\u00f3n de Lumen, y nuestro prop\u00f3sito de promover el progreso humano a trav\u00e9s de la tecnolog\u00eda en&nbsp;<\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/SqEPIKNhyUDM4nTDDUvBXBQeqpII-ZU_5c3i7AzCtr_6Cb6lhXoTWh0KtjRUhu2VDKOxU3ntjYdJC7fZWI2YvfmkP1hzwC4Zke9Z6etlMGEUrzzuP9wcf-qbYBNZ8vS3js_fClg4g9QLobk5WTvJke8jr6wpEEXNYO3Mvka_HGOgjc7E9xrW9bekAmeiiseaxRoNa9c\"><strong>news.lumen.com\/home<\/strong><\/a><strong>, LinkedIn:&nbsp;<\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/8PuzFshn7IzLeqzDmUVoOR8F3AkVxdk6N6HlY9AiZfxRszGUWR5J0rKvr9rG9iDURNEvnWlXB-QB212GLqfOIZ1DCqw6DyG3EmFOVHG3z_y819_67MR_NoEDdD3BFTWpBlcek6-mkCePO0ptnCfyCj_Xr0gQNF9hHzk-ooUJ8iM7KhSTxFB_ISZ290lLUyzZyp8UfTPrKE1WaeZTPjMEHiWFjw4Jnqt_WY5tIuUmt1zn\"><strong>\/lumentechnologies<\/strong><\/a><strong>, Twitter:&nbsp;<\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/GfqR-00iyfnegh74xLKpxLGww2pDdkQx1iWt8JHq_AmvCBGQ2kxWSjfd6GFpTT3cnwM0nVXouX-nccPmoLWmhafI7G-tTm7_1S4Zi2uhoaRKE6csjNOzVwjr0S9fLyAYtM4DuhH9IRTCbccDaCDN0yXEzrlxeYsh9ZE70vt7GuxyX7TL4poKrT4jhoS7cvlKSRMEm_6JNQ-n\"><strong>@lumentechco<\/strong><\/a><strong>, Facebook:&nbsp;<\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/IfrO4mhPdD6e2Xp1hLrYgQ-0wcmI-R3MlQJ8AOpzze94cCek3iXnXzK-3W6RC_Urr49Kqzg9QNC8liN_FohroatNA3Dm-jcQMLpFAzsf7FINtITFNe9Ftov0b4PERlKTSM_7RLBQqJ4dA5oB0WLogpbcP8VSkY5sZUUN7iiM4B5Pu4uQeEMJH9Na2DXbt3dnagdlgKXsjwNQrfRdG62HE-xPpHard3E\"><strong>\/lumentechnologies<\/strong><\/a><strong>, Instagram: @<\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/7x7dTk6hVh4lILBisjjma-DyEDbd7sGVgp_Ooql73IlAXqDSHwqHW2O6fNkO6lBjRvClZa3atqilFP7mIVtJLb-3cgkk38O7yk3vv51AEHcoiOjc_S0gQufAGlHcqeekVtsT2_DTynxzQ4tMiVuYk6mD-fRweLK8kDUT-tRlYWuD2M8Ct2VROxiuzAoKy8YTg1GCH--sWczgP80otp_n_NRs3DjRpIUNTMpjCqcZGZY655E\"><strong>lumentechnologies<\/strong><\/a><strong>&nbsp;y YouTube:&nbsp;<\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/7nm30.r.a.d.sendibm1.com\/mk\/cl\/f\/4Bs9fKKRJ_dZTasxlcRpgczeK0VzL596OzL38B3_89ysQN7DYCATR2_Prv-18BJVsnnqQQQiYEkB8NXADGEYL84yYORopvaARz3rKRDYuJ1Q44OP75XdTPR8wkbjVVvMbO944cLuZqAT5wuat9GWmwmzDGE0eelJYfowZ4ddh8V7AMMT6LJVpNijkf55Ap4QbP2H8jBSBqb3zrwigCCPA4o2bP4\"><strong>\/lumentechnologies<\/strong><\/a><strong>. Lumen y Lumen Technologies son marcas registradas en los Estados Unidos.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>luismart_ic@yahoo.com.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico, julio de 2022.-&nbsp;El metaverso gan\u00f3 el centro del escenario: este nuevo universo virtual e inmersivo que redefine la manera en que las personas interact\u00faan, se entretienen y trabajan, implica tambi\u00e9n nuevos desaf\u00edos para las organizaciones. El llamado \u201cmetaverso industrial\u201d o \u201cmetaverso de negocios\u201d promueve nuevos espacios para lanzar productos, realizar eventos con [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-502","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=502"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/502\/revisions"}],"predecessor-version":[{"id":503,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/502\/revisions\/503"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}