{"id":523,"date":"2022-08-04T13:18:23","date_gmt":"2022-08-04T18:18:23","guid":{"rendered":"http:\/\/ciencianews.in\/?p=523"},"modified":"2022-08-04T13:18:26","modified_gmt":"2022-08-04T18:18:26","slug":"ciencia-y-arte-elementos-indisolubles-de-la-humanidad","status":"publish","type":"post","link":"https:\/\/ciencianews.in\/index.php\/2022\/08\/04\/ciencia-y-arte-elementos-indisolubles-de-la-humanidad\/","title":{"rendered":"Ciencia y arte, elementos indisolubles de la humanidad"},"content":{"rendered":"\n<p><strong>Autor<\/strong><br>Direcci\u00f3n General de Comunicaci\u00f3n Social UNAM<br><strong>Fecha de publicaci\u00f3n<\/strong><br>03 de agosto 2022<br><strong>Categor\u00eda<\/strong><br>Bolet\u00edn<\/p>\n\n\n\n<p><em>\u2022 El libro&nbsp;<\/em>La Tabla de los Elementos&nbsp;<em>evoca ciencia, arte y colaboraci\u00f3n, destac\u00f3 Enrique Graue Wiechers<\/em><em><br>\u2022 Marcelo Ebrard Casaubon expres\u00f3 su compromiso por fortalecer la actividad cient\u00edfica, tecnol\u00f3gica, el arte y las humanidades de M\u00e9xico<br>\u2022 La obra es un retrato del Universo, de los elementos a trav\u00e9s de las mentes y manos de grandes y reconocidos artistas de M\u00e9xico y el mundo, coment\u00f3 Omar Fayad Meneses<\/em><\/p>\n\n\n\n<p>La ciencia y arte son elementos indisolubles de nuestra humanidad y son muestra de la necesidad cient\u00edfica de explorar y entender nuestro origen y el Universo, afirm\u00f3 el rector de la UNAM, Enrique Graue Wiechers, al participar en la presentaci\u00f3n del libro\u00a0<em>La Tabla de los Elementos<\/em>, esfuerzo editorial entre la Secretar\u00eda de Relaciones Exteriores (SRE), el Gobierno del estado de Hidalgo y\u00a0<em>La Cabra Ediciones<\/em><strong>.<\/strong><\/p>\n\n\n\n<p>En las p\u00e1ginas de esa obra, dijo, se re\u00fane mucho de lo mejor del ser humano: el genio del cient\u00edfico, su rigor metodol\u00f3gico y el deseo de progreso. \u201cAll\u00ed est\u00e1 el polvo de estrellas que dio origen a la vida, al color que nos rodea y las manifestaciones art\u00edsticas en toda su expresi\u00f3n humana\u201d.<\/p>\n\n\n\n<p>El libro, continu\u00f3, incluye un cat\u00e1logo de las obras de artistas que plasmaron las representaciones de todos los elementos de la tabla peri\u00f3dica y que en 2019 -como parte del A\u00f1o Internacional de la Tabla Peri\u00f3dica- fueron exhibidas en&nbsp;<em>Universum<\/em>, Museo de las Ciencias de la UNAM.<\/p>\n\n\n\n<p>En el Palacio de Miner\u00eda, Graue Wiechers tambi\u00e9n expuso que el texto evoca ciencia, arte y colaboraci\u00f3n. \u201cEs prueba de que cuando las instituciones trabajan de forma conjunta, los l\u00edmites se diluyen y se multiplica el alcance de sus logros individuales\u201d.<\/p>\n\n\n\n<p>Es, adem\u00e1s, un homenaje a la Tabla Peri\u00f3dica de los Elementos, punto de partida determinante en la historia de la ciencia y de su insaciable necesidad de explorar y entender nuestro origen y el Universo en el que nos desenvolvemos.<\/p>\n\n\n\n<p>En su oportunidad, el secretario de Relaciones Exteriores, Marcelo Ebrard Casaubon, felicit\u00f3 el esfuerzo para realizar esta obra que re\u00fane ciencia y que nos llenar\u00e1 de orgullo ante el mundo.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que la Canciller\u00eda promover\u00e1 el libro en diferentes pa\u00edses, \u201ctodo lo que podamos hacer para fortalecer la actividad cient\u00edfica, tecnol\u00f3gica y, por supuesto, el arte y las humanidades de M\u00e9xico, lo haremos con mucho gusto\u201d.<\/p>\n\n\n\n<p>Asimismo, subray\u00f3 que \u201cuna pol\u00edtica exterior sin una dimensi\u00f3n cient\u00edfica y cultural, o cultural y cient\u00edfica, pues es dif\u00edcil de imaginar porque no tendr\u00edamos buenos resultados, no ocupar\u00edamos el espacio que a M\u00e9xico le corresponde\u201d.<\/p>\n\n\n\n<p>En tanto, el gobernador del estado de Hidalgo, Omar Fayad Meneses, asever\u00f3 que esta es una pieza editorial \u00fanica, una interpretaci\u00f3n desde el arte de la tabla peri\u00f3dica, la cual es una representaci\u00f3n de la cultura en la ciencia y una de las m\u00e1s grandes innovaciones humanas.<\/p>\n\n\n\n<p>La noci\u00f3n de los elementos, record\u00f3, existe desde la Grecia cl\u00e1sica, pero&nbsp; fue hasta el siglo XIX cuando Dmitri Mendel\u00e9yev cre\u00f3 el sistema peri\u00f3dico, descrito por \u00e9l mismo como el mapa m\u00e1s hermoso de la humanidad para navegar por las entra\u00f1as de los \u00e1tomos y dominar las transformaciones de la materia. \u201cEl mundo cambi\u00f3 gracias a esta herramienta, pues es un lenguaje y patrimonio de la humanidad\u201d.<\/p>\n\n\n\n<p>De igual manera, apunt\u00f3, trasciende el arte, la ciencia y la pol\u00edtica; es un retrato del Universo, de los elementos a trav\u00e9s de las mentes y manos de grandes y destacados artistas de M\u00e9xico y el mundo. Hizo un reconocimiento al esfuerzo conjunto entre la Canciller\u00eda mexicana, el Gobierno del estado de Hidalgo y\u00a0<em>La Cabra Ediciones, y\u00a0<\/em>recalc\u00f3 que las mayores aportaciones para el mundo se realizan a partir de colaboraciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Diplomacia art\u00edstica-cient\u00edfica de M\u00e9xico<\/strong><\/h2>\n\n\n\n<p>El coordinador del Programa de Arte, Ciencia y Tecnolog\u00eda, de la UNAM, Jos\u00e9 Franco L\u00f3pez, calific\u00f3 al libro como extraordinario porque re\u00fane la participaci\u00f3n de 120 artistas pl\u00e1sticos y a un grupo de notables cient\u00edficos y divulgadores para generar un producto editorial que, a su vez, es un homenaje a la obra del ruso Dmitri Mendel\u00e9yev, \u201cquien orden\u00f3 los elementos qu\u00edmicos en una tabla que ha sido fundamental para el desarrollo de la ciencia en el siglo XX y adem\u00e1s representa el ADN de la materia ordinaria del Universo\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, cumple el deseo del Gobierno estatal por estar cerca de la ciencia y de la Canciller\u00eda de M\u00e9xico, por dimensionarlo como una obra de diplomacia art\u00edstica-cient\u00edfica de nuestro pa\u00eds para el mundo.<\/p>\n\n\n\n<p>En tanto, los directores de&nbsp;<em>La Cabra Ediciones<\/em>, Mar\u00eda Luisa Passarge y Rogelio Cu\u00e9llar, expresaron que el neur\u00f3logo Oliver Sacks fue el detonador del proyecto el cual, con su presentaci\u00f3n en el Palacio de Miner\u00eda, cerr\u00f3 un ciclo e inici\u00f3 otro.<\/p>\n\n\n\n<p>La tambi\u00e9n editora del libro explic\u00f3 que este es el cat\u00e1logo de la exposici\u00f3n que se mont\u00f3 en&nbsp;<em>Universum<\/em>&nbsp;de septiembre a noviembre de 2019, una fiesta donde artistas, cient\u00edficos y p\u00fablico en general convivieron y mostraron que la ciencia y el arte comparten creatividad, curiosidad, inteligencia y pasi\u00f3n. Adem\u00e1s, TV UNAM realiz\u00f3 el cortometraje \u201cLa tabla de los elementos\u201d, que recibi\u00f3 un premio en el Festival Pantalla de Cristal 2020, como mejor documental de arte.<\/p>\n\n\n\n<p>Al hacer uso de la palabra, Maribel Portela, artista y escultora participante en la obra, extern\u00f3 que la tabla peri\u00f3dica es el origen de la materia que constituye no solo al planeta sino al Universo; es una herramienta indispensable para descubrimientos cient\u00edficos y tambi\u00e9n para comprender el mundo que nos rodea, incluyendo al arte.<\/p>\n\n\n\n<p>\u201cMe gustar\u00eda pensar que el arte y la ciencia se abrazan, quiero suponer que es una afirmaci\u00f3n contundente de que el arte siempre ser\u00e1 el mejor ant\u00eddoto contra la incertidumbre global y cualquier amenaza que atente contra la libertad y la inteligencia. La Tabla Peri\u00f3dica de los Elementos se constituye como un manifiesto a favor de la belleza y del conocimiento en su lucha permanente contra la ignorancia\u201d, acot\u00f3.<\/p>\n\n\n\n<p>Rogelio Cu\u00e9llar, fot\u00f3grafo del cat\u00e1logo, refiri\u00f3 que este tipo de documentos son imprescindibles pues contribuyen a la formaci\u00f3n de p\u00fablicos y lectores, \u201cpermiten a los espectadores no depender de la memoria para tener el registro de la vivencia y relacionar lo visto y lo vivido en las exposiciones con textos y contenidos hist\u00f3ricos e intelectuales de la obra\u201d.<\/p>\n\n\n\n<p>Esta exposici\u00f3n y su cat\u00e1logo son una embajada cultural en M\u00e9xico a trav\u00e9s de la ciencia y el arte, un poderoso mensaje de diplomacia y reconocimiento a la creatividad mexicana. \u201cHa sido inolvidable la convivencia con 121 artistas que decidieron plasmar en un bastidor un elemento qu\u00edmico\u201d, abund\u00f3.<\/p>\n\n\n\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<br>Contacto: <a href=\"mailto:samcarbajalreportera@gmail.com\">samcarbajalreportera@gmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutorDirecci\u00f3n General de Comunicaci\u00f3n Social UNAMFecha de publicaci\u00f3n03 de agosto 2022Categor\u00edaBolet\u00edn \u2022 El libro&nbsp;La Tabla de los Elementos&nbsp;evoca ciencia, arte y colaboraci\u00f3n, destac\u00f3 Enrique Graue Wiechers\u2022 Marcelo Ebrard Casaubon expres\u00f3 su compromiso por fortalecer la actividad cient\u00edfica, tecnol\u00f3gica, el arte y las humanidades de M\u00e9xico\u2022 La obra es un retrato del Universo, de los elementos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-523","post","type-post","status-publish","format-standard","hentry","category-noticia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/comments?post=523"}],"version-history":[{"count":1,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/523\/revisions"}],"predecessor-version":[{"id":524,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/posts\/523\/revisions\/524"}],"wp:attachment":[{"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/media?parent=523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/categories?post=523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciencianews.in\/index.php\/wp-json\/wp\/v2\/tags?post=523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}